﻿{"id":4061,"date":"2026-07-15T07:50:49","date_gmt":"2026-07-15T05:50:49","guid":{"rendered":"https:\/\/manzanareselreal.org\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/"},"modified":"2026-07-15T07:50:49","modified_gmt":"2026-07-15T05:50:49","slug":"calle-de-las-cuatro-penas-38-manzanares-el-real","status":"publish","type":"tribe_venue","link":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/","title":{"rendered":"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4061","tribe_venue","type-tribe_venue","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real - Manzanares el Real<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real - Manzanares el Real\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzanares el Real\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/recinto\\\/calle-de-las-cuatro-penas-38-manzanares-el-real\\\/\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/recinto\\\/calle-de-las-cuatro-penas-38-manzanares-el-real\\\/\",\"name\":\"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real - Manzanares el Real\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\"},\"datePublished\":\"2026-07-15T05:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/recinto\\\/calle-de-las-cuatro-penas-38-manzanares-el-real\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/recinto\\\/calle-de-las-cuatro-penas-38-manzanares-el-real\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/recinto\\\/calle-de-las-cuatro-penas-38-manzanares-el-real\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\",\"name\":\"Manzanares el Real\",\"description\":\"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real - Manzanares el Real","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/","og_locale":"es_ES","og_type":"article","og_title":"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real - Manzanares el Real","og_url":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/","og_site_name":"Manzanares el Real","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/","url":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/","name":"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real - Manzanares el Real","isPartOf":{"@id":"https:\/\/manzanareselreal.org\/es\/#website"},"datePublished":"2026-07-15T05:50:49+00:00","breadcrumb":{"@id":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/manzanareselreal.org\/es\/recinto\/calle-de-las-cuatro-penas-38-manzanares-el-real\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/manzanareselreal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Calle de las Cuatro Pe\u00f1as, 38, Manzanares El Real"}]},{"@type":"WebSite","@id":"https:\/\/manzanareselreal.org\/es\/#website","url":"https:\/\/manzanareselreal.org\/es\/","name":"Manzanares el Real","description":"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manzanareselreal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_venue\/4061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_venue"}],"about":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/types\/tribe_venue"}],"author":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_venue\/4061\/revisions"}],"wp:attachment":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media?parent=4061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}