﻿{"id":4459,"date":"2026-07-15T07:57:50","date_gmt":"2026-07-15T05:57:50","guid":{"rendered":"https:\/\/manzanareselreal.org\/event\/programacion-noches-de-verano-2026\/"},"modified":"2026-07-15T07:57:50","modified_gmt":"2026-07-15T05:57:50","slug":"programacion-noches-de-verano-2026","status":"publish","type":"tribe_events","link":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/","title":{"rendered":"PROGRAMACI\u00d3N NOCHES DE VERANO 2026"},"content":{"rendered":"<p>T<br \/>\nTeatro, conciertos, circo, danza, observaci\u00f3n astron\u00f3mica y actividades participativas conforman una agenda variada que llenar\u00e1 de vida distintos espacios de nuestro municipio, convirtiendo las noches de verano en una oportunidad para disfrutar de la cultura al aire libre.\u00a0<br \/>\nAdem\u00e1s, parte de esta programaci\u00f3n se desarrolla en colaboraci\u00f3n con la Comunidad de Madrid a trav\u00e9s del programa Escenas de Verano, que acerca espect\u00e1culos y conciertos a los municipios de la regi\u00f3n.<\/p>\n<p>Programaci\u00f3n \u00abNoches de Verano\u00bb 2026<\/p>\n<p>\u00a0<br \/>\nViernes 3 de julio<br \/>\n\u00a0<\/p>\n<p>Espect\u00e1culo de circo: Eiren\u00ea \u2013 C\u00eda. La Troupe Malab\u00f3.<br \/>\n20:30 h &#8211; Plaza del Pueblo<br \/>\nFestival Cirqueando y Red de Teatros de la Comunidad de Madrid<br \/>\nUn grupo de artistas de circo y los vestigios de su carpa, se encuentran en medio de un conflicto b\u00e9lico. A pesar de las dificultades de un escenario tan excepcional, los protagonistas tratan de llevar su d\u00eda a d\u00eda entre alarmas antia\u00e9reas. Los personajes juegan a la guerra. Una historia contada con ternura, amor, humor, m\u00fasica y circo. Un mensaje de esperanza y paz<br \/>\n\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Domingo 5 de julio<br \/>\nConcierto cl\u00e1sico: Variaciones Goldberg\u00a0<br \/>\n21:00 h &#8211; Iglesia Ntra. Sra. de las Nieves<br \/>\nActividad gratuita. Acceso libre hasta completar aforo.<br \/>\nFestival Escenas de Verano CAM: Conciertos Cl\u00e1sicos en Verano<br \/>\nJohann Sebastian Bach<br \/>\nDiego Ares, clavicembalista<br \/>\n\u00a0<\/p>\n<p>\u00a0<br \/>\nCon tres Diapason d&#8217;or en su haber y el aprecio que le profesan tanto sus colegas como el p\u00fablico, Diego Ares se ha consolidado como uno de los int\u00e9rpretes de clave m\u00e1s influyentes de su generaci\u00f3n. Estudi\u00f3 piano con Aleksandras Jurgelionis y Aldona Dvarionait\u0117, y clave con Pilar Cancio, Richard Egarr, J\u00f6rg-Andreas B\u00f6tticher, Genoveva G\u00e1lvez y Carmen Schibli. Como solista ha tocado en los principales festivales de m\u00fasica antigua europeos, desarrollando paralelamente una notable actividad camer\u00edstica. Ha grabado para Columna M\u00fasica, Pan Classics, Harmonia Mundi, Mirare, el sello Prospero y el proyecto AllofBach.<br \/>\nSus discos han sido recibidos con entusiasmo por la prensa (tres veces \u00abExcepcional\u00bb por Scherzo, tres veces Diapason d&#8217;or, Maestro por Pianiste, Preis der Deutsche Schallplattenkritik, Choc por la revista Classica&#8230;) y ha impartido masterclasses en Espa\u00f1a, Polonia, Ruman\u00eda, Francia, Alemania y Suiza.<br \/>\n<iframe loading=\"lazy\" title=\"GOLDBERG VARIATIONS | Diego ARES (2020)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/oqaCEzAaXq4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Viernes 10 de julio<br \/>\nEspect\u00e1culo de circo: Play Time \u2013 C\u00eda. Chisgarab\u00eds &#038; Kambahiota Trup.<br \/>\n20:30 h- Plaza del Pueblo<br \/>\nFestival Cirqueando y Red de Teatros de la Comunidad de Madrid<\/p>\n<p>Jugar a manos llenas, implicarse al 100%, asumir riesgos,\u00a0olvidar el tiempo, disfrutar sin condiciones. En este momento ninguna otra cosa tiene importancia. Quiz\u00e1 nos mir\u00e9is de reojo, con miedo, envidia o verg\u00fcenza ajena. Nos tachar\u00e9is de insensatos. O tal vez os dej\u00e9is llevar por nuestro entusiasmo y particip\u00e9is junto a nosotros en un delirio colectivo que nos empuje a compartir un momento de libertad absoluta. \u00bfJuegas?<\/p>\n<p>S\u00e1bado 11 de julio<br \/>\nMaster Class de Bachata y Salsa<br \/>\n22:00 h &#8211; Plaza del Pueblo<\/p>\n<p>Master class de bachata y salsa con pareja de profesores de la Escuela de Danza manzanariega Zincal\u00f3.<br \/>\n\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Domingo 12 de julio<br \/>\nTaller de Circo<br \/>\n19:30 h- Plaza del Pueblo<br \/>\nFestival Cirqueando\u00a0<br \/>\nLos talleres estar\u00e1n dirigidos a ni\u00f1os y ni\u00f1as desde 4 a\u00f1os hasta los 12-13 y sus progenitores. Se enfocar\u00e1n a la iniciaci\u00f3n y descubrimiento de las artes circenses de una manera l\u00fadica y pedag\u00f3gica. Se propondr\u00e1n tres espacios de trabajo:<br \/>\n1- Cable de equilibrios aut\u00f3nomo.<br \/>\n2- Espacio con objetos de malabares con pelotas, pa\u00f1uelos, aros y di\u00e1bolos.<br \/>\n3- Bola de equilibrio<br \/>\nLa asociaci\u00f3n \u201cLa Tortuga Veloz\u201d responsable de la gesti\u00f3n de estos talleres tiene m\u00e1s de 15 a\u00f1os de experiencia dentro de la pedagog\u00eda circense, y cuenta con un equipo de profesionales de contrastada calidad.<\/p>\n<p>Viernes 17 de julio<br \/>\nUn Paseo por las Estrellas<br \/>\n22:00 h- Finca Valdelospi\u00e9s<br \/>\nNo requiere inscripci\u00f3n previa<\/p>\n<p>ESTRE Y TRELLA Un paseo por las estrellas.<\/p>\n<p>Observaci\u00f3n Astron\u00f3mica Teatralizada para todas la edades y capacidades.<\/p>\n<p>De la mano del Gu\u00eda de Estrellas, Jonat\u00e1n Fern\u00e1ndez, y la Actriz, Elena Mohedano, daremos un paseo por las estrellas; nombr\u00e1ndolas, reconoci\u00e9ndolas y gui\u00e1ndonos en la inmensidad del cielo nocturno. Conoceremos la historia de la astronom\u00eda desde la mitolog\u00eda a la ciencia. A trav\u00e9s de la observaci\u00f3n de los astros descifraremos las huellas de los eventos que escriben el firmamento. Personajes fugaces, ficticios y reales, cient\u00edficas notables, mitos y hasta estrellas de la canci\u00f3n espa\u00f1ola nos acompa\u00f1ar\u00e1n en esta divertida y entretenida Observaci\u00f3n Astron\u00f3mica Teatralizada.<\/p>\n<p>\u00a0<\/p>\n<p>S\u00e1bado 18 de julio<\/p>\n<p>Concierto: Mi Gran Noche\u2013 The GB Brothers<br \/>\n22:00 h &#8211; Plaza del Pueblo<\/p>\n<p>La Plaza del Pueblo de Manzanares el Real ser\u00e1 el escenario de una velada musical protagonizada por THE GB BROTHERS, d\u00fao formado por piano y viol\u00edn. A trav\u00e9s de un repertorio cuidadosamente seleccionado, ambos int\u00e9rpretes ofrecer\u00e1n un recorrido lleno de elegancia, virtuosismo y emoci\u00f3n.<br \/>\nEn el incomparable entorno de uno de los enclaves m\u00e1s emblem\u00e1ticos de la Sierra de Guadarrama, este concierto invita a disfrutar de una experiencia \u00fanica al aire libre, donde la m\u00fasica, el patrimonio y el ambiente de la plaza se unen para crear una noche inolvidable.<br \/>\n\u00a0<\/p>\n<p>Domingo 19 de julio<br \/>\nConcierto cl\u00e1sico: La voix de la viole<br \/>\n21:00 h &#8211; Iglesia Ntra. Sra. de las Nieves<br \/>\nActividad gratuita. Acceso libre hasta completar aforo.<br \/>\nFestival Escenas de Verano CAM: Conciertos Cl\u00e1sicos en Verano.<\/p>\n<p>Obras de M. Marais y F. Couperin<br \/>\nLa Bellemont<br \/>\nSara Ruiz, viola da gamba \u2013 Rafael Mu\u00f1oz, la\u00fad &#8211; Laura Puerto, clave.<br \/>\nLa uni\u00f3n de la m\u00fasica con la ret\u00f3rica es una de las caracter\u00edsticas fundamentales de la m\u00fasica barroca. Tanto al amparo de los manuales de ret\u00f3rica musical como bajo una influencia siempre latente que salpic\u00f3 a todas las artes, la oratoria fue el modelo en el que se inspiraron todos los compositores barrocos. Seg\u00fan Quantz, \u201cla interpretaci\u00f3n musical puede compararse al discurso de un orador\u201d.<br \/>\nEl programa La voix de la viole gira en torno a esta idea a trav\u00e9s de dos de los compositores m\u00e1s importantes del barroco franc\u00e9s: Marain Marais y Fran\u00e7ois Couperin. Con la suite en mi menor Couperin explora los afectos m\u00e1s tristes a trav\u00e9s de movimientos descendentes, saltos mel\u00f3dicos que recuerdan a exclamaciones de tristeza, o movimientos de la voz que parecen suspiros. Por su parte Marais toma un punto de partida m\u00e1s noble y severo en sus piezas en la menor, que completa con una carga emocional muy intensa al usar el cromatismo o un cierto di\u00e1logo entre la viola y el bajo continuo a modo de conflicto constante. El programa se completa con piezas descriptivas como Les Bergeries, en la que Couperin retrata la inocencia y deleite de unos pastores que trabajan en un escenario campestre buc\u00f3lico. A su vez Marais describe genialmente en su colosal Labyrinth la incertidumbre de un hombre que se ha perdido en el laberinto de Versalles y completa con las paradigm\u00e1ticas Folies d\u2019Espagne un retrato del lenguaje franc\u00e9s para la viola.<br \/>\nLa voix de la viole es un programa que muestra la voz de la viola da gamba, instrumento considerado en la \u00e9poca como el que \u201cimita a la perfecci\u00f3n a la voz en todas sus modulaciones y afectos, convirti\u00e9ndose en la perfecta oradora\u201d.<\/p>\n<p>Biograf\u00eda de La Bellemont<br \/>\nTras casi veinte a\u00f1os de trayectoria, La Bellemont se ha posicionado en Espa\u00f1a como un conjunto de referencia en la interpretaci\u00f3n de la m\u00fasica barroca. Sus miembros son colaboradores habituales en conjuntos de m\u00fasica antigua espa\u00f1oles y europeos que desarrollan su actividad pedag\u00f3gica en diferentes conservatorios superiores. La Bellemont nace en 2007 con la voluntad de lograr una interpretaci\u00f3n muy personal del repertorio para viola da gamba y bajo continuo trabajando intensamente en el sonido, la gestualidad y la articulaci\u00f3n del conjunto. Su primer \u00e1lbum titulado La voix de la viole ha sido elogiado por la cr\u00edtica (5 Diapasons en la revista Diapason) destacando la elegancia, el perfeccionismo, la fuerza expresiva y el placer por el sonido per se, que se han convertido en el sello de identidad del grupo. Su segundo \u00e1lbum, Plaisir Sacr\u00e9, super\u00f3 las expectativas siendo nominado a los premios ICMA. Las suites para viola da gamba y continuo de Fran\u00e7ois Couperin cerrar\u00e1n esta trilog\u00eda basada en el repertorio barroco franc\u00e9s y se publicar\u00e1n en agosto de 2026.<br \/>\nLa Bellemont ampl\u00eda su repertorio a la Alemania de Bach y sus predecesores, as\u00ed como al Renacimiento espa\u00f1ol y el seicento italiano ofreciendo programas en una amplia variedad de plantillas. El programa Choralfantasie con transcripciones para grupo instrumental de grandes obras de \u00f3rgano de Bach, ha conseguido excelentes cr\u00edticas en las que se resalta la capacidad del grupo de \u201cflirtear con la perfecci\u00f3n\u201d (Revista Scherzo).\u00a0<br \/>\nFicha art\u00edstica<br \/>\nSara Ruiz, viola da gamba<br \/>\nRafael Mu\u00f1oz, tiorba<br \/>\nLaura Puerto, clave<\/p>\n<p>Jueves 23 de julio<br \/>\nEspect\u00e1culo: Arte en Vivo en la Plaza<br \/>\n20:30 h- Plaza del Pueblo<br \/>\nFestival Escenas de Verano CAM<\/p>\n<p>Este verano, la Comunidad de Madrid vuelve con\u00a0Arte vivo en la plaza, un programa que celebra y difunde\u00a0el talento creativo mediante acciones art\u00edsticas din\u00e1micas y participativas\u00a0ancladas en el alma de los pueblos: sus plazas, espacios conocidos y comunes por y para todos, y reinvent\u00e1ndolas a trav\u00e9s del prisma del arte.<br \/>\nEstos espacios, epicentros de la vida comunal, se convertir\u00e1n en lienzos vivientes donde el arte nace y se comparte sin reservas: un total de once encuentros donde cinco artistas contempor\u00e1neos dar\u00e1n vida a sus creaciones ante los ojos del p\u00fablico, invit\u00e1ndoles a\u00a0explorarlas\u00a0saliendo de los l\u00edmites habituales de los museos, salas de exposiciones y galer\u00edas.<br \/>\nM\u00f3nica Mura, Sara Gema, Mocholi,\u00a0Yolanda Andr\u00e9s y\u00a0Julio Linares son el equipo art\u00edstico\u00a0que compartir\u00e1\u00a0estos espacios p\u00fablicos en encuentros con una duraci\u00f3n de noventa minutos. Una oportunidad para conocer sus trabajos y creaciones de primera mano, conversar con ellos, intercambiar ideas y descubrir nuevos m\u00e9todos de trabajo.<br \/>\nArte vivo en la plaza 2026 | Comunidad de Madrid<\/p>\n<p>Viernes 24 de julio<br \/>\nEspect\u00e1culo Folcl\u00f3rico: Grupo Folcl\u00f3rico de Becerril de la Sierra y Vasilitzia Folklore Group<br \/>\n20:30h &#8211; Plaza del Pueblo<br \/>\nEl Grupo Folclorico de Becerril de la Sierra tiene como objetivo principal la conservaci\u00f3n y posterior difusi\u00f3n de nuestro rico folclore nacional, y muy especialmente, el de nuestra regi\u00f3n madrile\u00f1a. \u00c9sta es la idea com\u00fan de sus miembros que, de manera desinteresada, disfrutan realizando la labor mediante ensayos semanales, aprendiendo los pasos, las canciones, los ritmos y las melod\u00edas, confeccionando sus propios trajes t\u00edpicos, para poder mostrar a sus gentes y a los pueblos vecinos todo aquello aprendido y realizado durante los ensayos.<br \/>\nSu repertorio folcl\u00f3rico se basa fundamentalmente en piezas aut\u00f3ctonas de toda la Sierra de Guadarrama, sin olvidar aquellas de la capital, del sur de la Comunidad de Madrid y otras danzas serranas del \u00e1rea fronteriza con la Sierra de Gredos. La influencia segoviana en la Sierra de Guadarrama es notoria en la poblaci\u00f3n, y algunos de los cantos y danzas que las gentes serranas a\u00fan conocen proceden de nuestra vecina provincia, muy enlazada hist\u00f3ricamente a la sierra madrile\u00f1a por motivos de rivalidad jurisdiccional y territorial entre madrile\u00f1os y segovianos habidos en la zona siglos atr\u00e1s.<br \/>\nConcurso de DJ&#8217;s<br \/>\n22:30 h &#8211; Plaza del Pueblo<\/p>\n<p>S\u00e9ptima edici\u00f3n del Concurso de DJ\u00b4s promovido por el \u00e1rea de Juventud con el objetivo de favorecer la expresi\u00f3n art\u00edstica y la participaci\u00f3n de los j\u00f3venes.<\/p>\n<p>S\u00e1bado 25 de julio<br \/>\nFestival Pedriza Rock<br \/>\n21:00 h &#8211; Plaza del Pueblo<\/p>\n<p>Decimoctava edici\u00f3n del cl\u00e1sico festival de Rock.<\/p>\n<p>Domingo 26 de julio<br \/>\nEspect\u00e1culo musical: Broadway<br \/>\n20:30 h- Plaza del Pueblo<\/p>\n<p>Muestra del taller de Teatro Musical de la Escuela de Danza Zincal\u00f3.<br \/>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T Teatro, conciertos, circo, danza, observaci\u00f3n astron\u00f3mica y actividades participativas conforman una agenda variada que llenar\u00e1 de vida distintos espacios de nuestro municipio, convirtiendo las noches de verano en una&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4460,"template":"","format":"standard","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4459","tribe_events","type-tribe_events","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROGRAMACI\u00d3N NOCHES DE VERANO 2026 - Manzanares el Real<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROGRAMACI\u00d3N NOCHES DE VERANO 2026 - Manzanares el Real\" \/>\n<meta property=\"og:description\" content=\"T Teatro, conciertos, circo, danza, observaci\u00f3n astron\u00f3mica y actividades participativas conforman una agenda variada que llenar\u00e1 de vida distintos espacios de nuestro municipio, convirtiendo las noches de verano en una&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzanares el Real\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/\",\"name\":\"PROGRAMACI\u00d3N NOCHES DE VERANO 2026 - Manzanares el Real\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NOCHES-DE-VERANO-PROGRAMACION-2026-1-scaled-1.jpg\",\"datePublished\":\"2026-07-15T05:57:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NOCHES-DE-VERANO-PROGRAMACION-2026-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/NOCHES-DE-VERANO-PROGRAMACION-2026-1-scaled-1.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/programacion-noches-de-verano-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/agenda_alternativa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PROGRAMACI\u00d3N NOCHES DE VERANO 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\",\"name\":\"Manzanares el Real\",\"description\":\"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROGRAMACI\u00d3N NOCHES DE VERANO 2026 - Manzanares el Real","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/","og_locale":"es_ES","og_type":"article","og_title":"PROGRAMACI\u00d3N NOCHES DE VERANO 2026 - Manzanares el Real","og_description":"T Teatro, conciertos, circo, danza, observaci\u00f3n astron\u00f3mica y actividades participativas conforman una agenda variada que llenar\u00e1 de vida distintos espacios de nuestro municipio, convirtiendo las noches de verano en una&hellip;","og_url":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/","og_site_name":"Manzanares el Real","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/","url":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/","name":"PROGRAMACI\u00d3N NOCHES DE VERANO 2026 - Manzanares el Real","isPartOf":{"@id":"https:\/\/manzanareselreal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/#primaryimage"},"image":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/NOCHES-DE-VERANO-PROGRAMACION-2026-1-scaled-1.jpg","datePublished":"2026-07-15T05:57:50+00:00","breadcrumb":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/#primaryimage","url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/NOCHES-DE-VERANO-PROGRAMACION-2026-1-scaled-1.jpg","contentUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/NOCHES-DE-VERANO-PROGRAMACION-2026-1-scaled-1.jpg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/manzanareselreal.org\/es\/evento\/programacion-noches-de-verano-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/manzanareselreal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/manzanareselreal.org\/es\/agenda_alternativa\/"},{"@type":"ListItem","position":3,"name":"PROGRAMACI\u00d3N NOCHES DE VERANO 2026"}]},{"@type":"WebSite","@id":"https:\/\/manzanareselreal.org\/es\/#website","url":"https:\/\/manzanareselreal.org\/es\/","name":"Manzanares el Real","description":"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manzanareselreal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events\/4459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events\/4459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/4460"}],"wp:attachment":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media?parent=4459"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tags?post=4459"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=4459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}