﻿{"id":4401,"date":"2026-07-15T07:56:48","date_gmt":"2026-07-15T05:56:48","guid":{"rendered":"https:\/\/manzanareselreal.org\/event\/mercado-artesano-especial-tejedoras\/"},"modified":"2026-07-15T07:56:48","modified_gmt":"2026-07-15T05:56:48","slug":"mercado-artesano-especial-tejedoras","status":"publish","type":"tribe_events","link":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/","title":{"rendered":"MERCADO ARTESANO: ESPECIAL TEJEDORAS"},"content":{"rendered":"<p>Los pr\u00f3ximos 6 y 7 de junio, Manzanares El Real acoger\u00e1 una nueva edici\u00f3n del Mercado Artesano llamado el Mercado de las Tejedoras, con un espacio con talleres para tejer, hacer manualidades, y puestos de artesanos. Adem\u00e1s, con motivo de la celebraci\u00f3n del\u00a0D\u00eda de Tejer en P\u00fablico, las tejedoras de la\u00a0Asociaci\u00f3n de Mayores +60\u00a0y la\u00a0Asociaci\u00f3n de Mayores\u00a0estar\u00e1n mostrando sus trabajos y ense\u00f1ando esta labor tradicional a todas las personas que quieran acercarse a conocer y aprender esta actividad.<br \/>\nDurante ambas jornadas, las tejedoras estar\u00e1n en\u00a0una carpa propia en horario de\u00a010:00 a 14:00 horas.<\/p>\n<p>Talleres participativos<br \/>\nAdem\u00e1s, el mercado contar\u00e1 con talleres abiertos para disfrutar en familia y aprender de forma sostenible:<br \/>\nTaller de setitas limoneras<br \/>\nS\u00e1bado 6 y domingo 7 de junio<br \/>\nA partir de las 12:00 horas<br \/>\nUna propuesta para decorar de manera creativa con limones.<br \/>\nTaller de colgador de plantas<br \/>\nDomingo 7 de junio<br \/>\nA las 12:00 horas<br \/>\nLas personas participantes deber\u00e1n traer su propia maceta para realizar la actividad.<\/p>\n<p>\u00a0<\/p>\n<p>Del 6 y 7 de junio de 2026<\/p>\n<p>Plaza del Pueblo<\/p>\n<p>Horario:<\/p>\n<p>S\u00e1bado 10:00 a 20:00<\/p>\n<p>Domingo 10:00 a 15:00<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los pr\u00f3ximos 6 y 7 de junio, Manzanares El Real acoger\u00e1 una nueva edici\u00f3n del Mercado Artesano llamado el Mercado de las Tejedoras, con un espacio con talleres para tejer,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4402,"template":"","format":"standard","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4401","tribe_events","type-tribe_events","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MERCADO ARTESANO: ESPECIAL TEJEDORAS - Manzanares el Real<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MERCADO ARTESANO: ESPECIAL TEJEDORAS - Manzanares el Real\" \/>\n<meta property=\"og:description\" content=\"Los pr\u00f3ximos 6 y 7 de junio, Manzanares El Real acoger\u00e1 una nueva edici\u00f3n del Mercado Artesano llamado el Mercado de las Tejedoras, con un espacio con talleres para tejer,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzanares el Real\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/\",\"name\":\"MERCADO ARTESANO: ESPECIAL TEJEDORAS - Manzanares el Real\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/tejedoras-2026.jpg\",\"datePublished\":\"2026-07-15T05:56:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/tejedoras-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/tejedoras-2026.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/mercado-artesano-especial-tejedoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/agenda_alternativa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MERCADO ARTESANO: ESPECIAL TEJEDORAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\",\"name\":\"Manzanares el Real\",\"description\":\"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MERCADO ARTESANO: ESPECIAL TEJEDORAS - Manzanares el Real","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/","og_locale":"es_ES","og_type":"article","og_title":"MERCADO ARTESANO: ESPECIAL TEJEDORAS - Manzanares el Real","og_description":"Los pr\u00f3ximos 6 y 7 de junio, Manzanares El Real acoger\u00e1 una nueva edici\u00f3n del Mercado Artesano llamado el Mercado de las Tejedoras, con un espacio con talleres para tejer,&hellip;","og_url":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/","og_site_name":"Manzanares el Real","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/","url":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/","name":"MERCADO ARTESANO: ESPECIAL TEJEDORAS - Manzanares el Real","isPartOf":{"@id":"https:\/\/manzanareselreal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/#primaryimage"},"image":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/#primaryimage"},"thumbnailUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/tejedoras-2026.jpg","datePublished":"2026-07-15T05:56:48+00:00","breadcrumb":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/#primaryimage","url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/tejedoras-2026.jpg","contentUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/tejedoras-2026.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/manzanareselreal.org\/es\/evento\/mercado-artesano-especial-tejedoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/manzanareselreal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/manzanareselreal.org\/es\/agenda_alternativa\/"},{"@type":"ListItem","position":3,"name":"MERCADO ARTESANO: ESPECIAL TEJEDORAS"}]},{"@type":"WebSite","@id":"https:\/\/manzanareselreal.org\/es\/#website","url":"https:\/\/manzanareselreal.org\/es\/","name":"Manzanares el Real","description":"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manzanareselreal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events\/4401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events\/4401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/4402"}],"wp:attachment":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media?parent=4401"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tags?post=4401"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=4401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}