﻿{"id":4222,"date":"2026-07-15T07:53:49","date_gmt":"2026-07-15T05:53:49","guid":{"rendered":"https:\/\/manzanareselreal.org\/event\/documental-descansa-en-paz\/"},"modified":"2026-07-15T07:53:49","modified_gmt":"2026-07-15T05:53:49","slug":"documental-descansa-en-paz","status":"publish","type":"tribe_events","link":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/","title":{"rendered":"DOCUMENTAL \u00abDESCANSA EN PAZ\u00bb"},"content":{"rendered":"<p>El pr\u00f3ximo 27 de marzo, tendr\u00e1 lugar la proyecci\u00f3n del documental \u201cDescansa en Paz\u201d, que visibiliza la situaci\u00f3n de los cementerios en Espa\u00f1a y las dificultades de acceso a una sepultura digna conforme a la confesi\u00f3n musulmana.<\/p>\n<p>\u00a0<\/p>\n<p>Durante el encuentro se compartir\u00e1n algunos de los resultados de investigaci\u00f3n del proyecto y se dar\u00e1 visibilidad al documental, que recoge testimonios y visitas a cementerios de diferentes territorios para entender c\u00f3mo se est\u00e1n garantizando (o no) estos derechos en Espa\u00f1a.<br \/>\nContamos adem\u00e1s con la participaci\u00f3n de\u00a0Carlos Hern\u00e1ndez Fern\u00e1ndez, doctor en Ciencias Sociales, soci\u00f3logo, periodista y especialista en duelo. Profesor en la Universidad Pontificia Comillas y autor de libros como &#8216;Nadie deber\u00eda morir solo&#8217; o &#8216;Como hojas en oto\u00f1o: Gu\u00eda pr\u00e1ctica para comprender la muerte y el duelo&#8217;, aportar\u00e1 una mirada experta sobre la muerte, el acompa\u00f1amiento y los rituales contempor\u00e1neos.<br \/>\nDespu\u00e9s del visionado abriremos un espacio de conversaci\u00f3n con la ciudadan\u00eda para compartir reflexiones, preguntas y caminos posibles. Porque hablar de dignidad, derechos y convivencia tambi\u00e9n forma parte de construir comunidad.<\/p>\n<p>Viernes 27 de marzo<\/p>\n<p>De 18:00 a 20:00 h<\/p>\n<p>Sala El Rodaje<\/p>\n<p>\u00a0<\/p>\n<p>Si quieres asistir, reg\u00edstrate previamente y avisa en caso de no poder acudir:<\/p>\n<p>\u00a0info@entierrodigno.es<\/p>\n<p>\u00a0<\/p>\n<p>Despu\u00e9s de la proyecci\u00f3n habr\u00e1 una charla coloquio que invitar\u00e1 a reflexionar, escuchar y avanzar hacia una sociedad m\u00e1s justa y respetuosa.<\/p>\n<p>M\u00e1s informaci\u00f3n:\u00a0<\/p>\n<p>https:\/\/entierro-digno.movements.mov\/ev\/proyeccion-descansa-en-paz-en-manzanares-el-real<\/p>\n<p>Una invitaci\u00f3n a conocer la realidad de los cementerios con parcelas para personas musulmanas en distintos municipios de Espa\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 27 de marzo, tendr\u00e1 lugar la proyecci\u00f3n del documental \u201cDescansa en Paz\u201d, que visibiliza la situaci\u00f3n de los cementerios en Espa\u00f1a y las dificultades de acceso a una&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4223,"template":"","format":"standard","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4222","tribe_events","type-tribe_events","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DOCUMENTAL &quot;DESCANSA EN PAZ&quot; - Manzanares el Real<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DOCUMENTAL &quot;DESCANSA EN PAZ&quot; - Manzanares el Real\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 27 de marzo, tendr\u00e1 lugar la proyecci\u00f3n del documental \u201cDescansa en Paz\u201d, que visibiliza la situaci\u00f3n de los cementerios en Espa\u00f1a y las dificultades de acceso a una&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzanares el Real\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/\",\"name\":\"DOCUMENTAL \\\"DESCANSA EN PAZ\\\" - Manzanares el Real\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-03-10-at-13.05.24.jpeg\",\"datePublished\":\"2026-07-15T05:53:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-03-10-at-13.05.24.jpeg\",\"contentUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-03-10-at-13.05.24.jpeg\",\"width\":1280,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/evento\\\/documental-descansa-en-paz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/agenda_alternativa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DOCUMENTAL \u00abDESCANSA EN PAZ\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\",\"name\":\"Manzanares el Real\",\"description\":\"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DOCUMENTAL \"DESCANSA EN PAZ\" - Manzanares el Real","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/","og_locale":"es_ES","og_type":"article","og_title":"DOCUMENTAL \"DESCANSA EN PAZ\" - Manzanares el Real","og_description":"El pr\u00f3ximo 27 de marzo, tendr\u00e1 lugar la proyecci\u00f3n del documental \u201cDescansa en Paz\u201d, que visibiliza la situaci\u00f3n de los cementerios en Espa\u00f1a y las dificultades de acceso a una&hellip;","og_url":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/","og_site_name":"Manzanares el Real","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/","url":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/","name":"DOCUMENTAL \"DESCANSA EN PAZ\" - Manzanares el Real","isPartOf":{"@id":"https:\/\/manzanareselreal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/#primaryimage"},"image":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-03-10-at-13.05.24.jpeg","datePublished":"2026-07-15T05:53:49+00:00","breadcrumb":{"@id":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/#primaryimage","url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-03-10-at-13.05.24.jpeg","contentUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-03-10-at-13.05.24.jpeg","width":1280,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/manzanareselreal.org\/es\/evento\/documental-descansa-en-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/manzanareselreal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/manzanareselreal.org\/es\/agenda_alternativa\/"},{"@type":"ListItem","position":3,"name":"DOCUMENTAL \u00abDESCANSA EN PAZ\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/manzanareselreal.org\/es\/#website","url":"https:\/\/manzanareselreal.org\/es\/","name":"Manzanares el Real","description":"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manzanareselreal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events\/4222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events\/4222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/4223"}],"wp:attachment":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media?parent=4222"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tags?post=4222"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=4222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}