﻿{"id":1032,"date":"2025-09-24T10:54:15","date_gmt":"2025-09-24T08:54:15","guid":{"rendered":"https:\/\/openideas.site\/manzanareselreal\/es\/?post_type=que-ver&#038;p=1032"},"modified":"2025-10-30T11:35:47","modified_gmt":"2025-10-30T10:35:47","slug":"iglesia-de-nuestra-senora-de-las-nieves","status":"publish","type":"que-ver","link":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/","title":{"rendered":"Iglesia de Nuestra Se\u00f1ora de las Nieves"},"content":{"rendered":"<p>\u00cd\u00f1igo L\u00f3pez de Mendoza y Luna, II Duque del Infantado, incorpor\u00f3 en la obra del Castillo Nuevo la parroquia de la Virgen de la Nava, iglesia tradicional de culto de la Villa. Ante esta expropiaci\u00f3n al pueblo, a finales del siglo XV encarg\u00f3 la construcci\u00f3n de una nueva iglesia que recogiera, a su vez, la fe de los manzanariegos y los nuevos c\u00e1nones art\u00edsticos de la \u00e9poca.<\/p>\n<p>Nuestra Se\u00f1ora de las Nieves nos muestra su b\u00f3veda dise\u00f1ada por Juan Guas, arquitecto de los Reyes Cat\u00f3licos, o los avatares a los que ha sobrevivido, como sus tempranas ampliaciones, incendios y la mima Guerra Civil.<\/p>\n<p>Su actual jard\u00edn, antiguo campo santo, no es menos importante, ya que conserva magn\u00edficas estelas funerarias de los siglos XIII y XIV.<\/p>\n","protected":false},"featured_media":3194,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"que-visitar":[19],"class_list":["post-1032","que-ver","type-que-ver","status-publish","format-standard","has-post-thumbnail","hentry","que-visitar-castillo-de-manzanares-el-real-guia-completa-para-tu-visita"],"acf":{"caracteristicas":["Adecuado_para_ninos","Accesibilidad_fisica"],"que_ver_cabecera_archivo":{"que_ver_cabecera_archivo_nombre":"","que_ver_cabecera_archivo_url":""},"que_ver_cabecera_audio":{"que_ver_cabecera_audio_nombre":"Audiogu\u00eda","que_ver_cabecera_audio_url":"https:\/\/manzanareselreal.org\/siteresources\/files\/audio\/turismo\/iglesia-de-nuestra-sra-de-las-nieves.mp3"},"que_ver_alerta":false,"que_ver_alerta_contenido":{"que_ver_alerta_contenido_tipo":false,"que_ver_alerta_contenido_texto":""},"que_ver_subtitulo_titulo":"Una nueva parroquia para la \u00e9poca de mayor esplendor","que_ver_subtitulo_descripcion":"Recuper\u00f3 la fe que los duques quitaron al pueblo, representa la grandeza como templo de la Villa que fue cabeza del Real de Manzanares.","que_ver_espacio_abierto":false,"que_ver_contenido_izquierda_titulo":"Iglesia de Nuestra Se\u00f1ora de las Nieves","que_ver_contenido_izquierda_direccion":"Pl. del Sagrado Coraz\u00f3n, 1, 28410 Manzanares el Real, Madrid","que_ver_contenido_izquierda_contacto":"","que_ver_contenido_izquierda_horario":"Lunes: Cerrado,\r\nMartes: 19:00  - 19:30   20:00 - 20:30,\r\nMi\u00e9rcoles: 19:00  - 19:30   20:00 - 20:30,\r\nJueves: 19:00  - 19:30   20:00 - 20:30,\r\nViernes: 19:00  - 19:30   20:00 - 20:30,\r\nS\u00e1bado: 19:00  - 19:30   20:00 - 20:30,\r\nDomingo: 09:30 - 10:00  12:00-12:30","que_ver_contenido_izquierda_enlaces":"","que_ver_normativas_oficiales":[{"que_ver_normativas_oficiales_texto":"Ley 16\/1985, de 25 de junio, del Patrimonio Hist\u00f3rico Espa\u00f1ol","que_ver_normativas_oficiales_enlace":"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-1985-12534"},{"que_ver_normativas_oficiales_texto":"Ley 3\/2013, de 18 de junio, de Patrimonio Hist\u00f3rico de la Comunidad de Madrid","que_ver_normativas_oficiales_enlace":"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2013-10725&p=20140815&tn=2"}],"contenido_central":"","que_ver_contenido_extra":true,"que_ver_contenido_extra_titulo":"La iglesia de Manzanares El Real","que_ver_contenido_extra_descripcion":"Una larga e interesante vida, de noble origen pero con azarosas experiencias","que_ver_contenido_acordeon":[{"que_ver_contenido_acordeon_titulo":"1495","que_ver_contenido_acordeon_descripcion":"<table cellpadding=\"20\">\r\n<tbody>\r\n<tr>\r\n<td>La primera noticia que tenemos de la construcci\u00f3n de la Iglesia la encontramos en los textos hist\u00f3ricos de 1495, aunque es probable que ya estuviera en construcci\u00f3n a\u00f1os antes cuando \u00cd\u00f1igo L\u00f3pez de Mendoza y Luna, II Duque del Infantado, cambi\u00f3 el proyecto del Castillo Nuevo para integrar en \u00e9l la antigua parroquia de la Virgen de la Nava. Esta decisi\u00f3n hizo necesaria la edificaci\u00f3n de una nueva iglesia parroquial, por lo que ambas obras se realizaron al mismo tiempo y participaron en el templo Juan Guas, autor de la Galer\u00eda Sur del Castillo, y el arquitecto del Gran Cardenal Mendoza, Lorenzo V\u00e1zquez de Segovia.<\/td>\r\n<td width=\"500\"><img class=\"alignnone size-medium\" src=\"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/qv-41.jpg\" alt=\"\" width=\"100%\" \/><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>"},{"que_ver_contenido_acordeon_titulo":"Arquitectura","que_ver_contenido_acordeon_descripcion":"<table cellpadding=\"20\">\r\n<tbody>\r\n<tr>\r\n<td>La Iglesia de Nuestra Se\u00f1ora de las Nieves cuenta con una planta de tres naves separadas por arquer\u00edas. La cabecera, cubierta de una soberbia b\u00f3veda de crucer\u00eda realizada con piezas de yeso imitando piedra caliza, presenta las uniones de sus nervios decorados con pinturas. Fue dise\u00f1ada por el genial Juan Guas en un ejercicio de arquitectura muy singular. A los pies, el coro ha sido recientemente reconstruido con dos de las cuatro columnas que ten\u00eda originariamente. Sus capiteles son id\u00e9nticos a los del p\u00f3rtico del ayuntamiento, obra de Lorenzo V\u00e1zquez de Segovia. La torre, adosada a la esquina noroeste, cuenta con tres cuerpos que se separan por cornisas y las t\u00edpicas bolas mendocinas de estilo isabelino. En ella se abren dos alturas de huecos para las campanas con barandillas labradas en forma de flor de cuatro p\u00e9talos. Resulta curioso el hueco circular del piso inferior decorado con un trisquel, aunque solo el de la cara sur es original.\r\n\r\nLa ampliaci\u00f3n del templo hacia el sur, documentada en 1511, responde m\u00e1s a los c\u00e1nones renacentistas incorporando la siller\u00eda en la sacrist\u00eda y un atrio porticado a lo largo de la fachada. Adem\u00e1s, las imponentes arquer\u00edas de medio punto, que separan la nave central de las laterales, parecen haber sido a\u00f1adidas al proyecto cuando la cabecera ya estaba construida pues son demasiado estrechas. Se a\u00f1adieron tambi\u00e9n potentes contrafuertes exteriores en la cabecera y a los pies del edificio para contrarrestar los empujes laterales de un proyecto arriesgado.<\/td>\r\n<td width=\"500\"><img class=\"alignnone size-medium\" src=\"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/qv-42.jpg\" alt=\"\" width=\"100%\" \/><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>"},{"que_ver_contenido_acordeon_titulo":"El incendio de 1769","que_ver_contenido_acordeon_descripcion":"<table cellpadding=\"20\">\r\n<tbody>\r\n<tr>\r\n<td>La Iglesia ha sufrido graves da\u00f1os a lo largo de su historia, aunque el m\u00e1s importante fue el incendio que se produjo de 1769 durante las fiestas de la Virgen de Pe\u00f1a Sacra. Ardi\u00f3 la torre, la capilla del baptisterio, todo el artesonado, gran parte de las im\u00e1genes de culto y parte del archivo. Milagrosamente, se salvaron la cabecera, la sacrist\u00eda y el retablo mayor, aunque este \u00faltimo fue destruido durante la Guerra Civil. Junto al techo del p\u00f3rtico y sobre la puerta de entrada, se conserva una viga labrada procedente del artesonado original, la \u00fanica que se libr\u00f3 del incendio. La iglesia fue reconstruida y, tras varios siglos de dificultades en su mantenimiento, sufre una importante restauraci\u00f3n entre 1969 y 1970. Es entonces cuando se pierde parte del cementerio interior y otros elementos, como las l\u00e1pidas sepulcrales, el p\u00falpito y el coro. Ya en 2012, la iglesia recuper\u00f3 sus vol\u00famenes originales y, actualmente, el coro alberga una exposici\u00f3n con diversos objetos recuperados durante la restauraci\u00f3n del templo.<\/td>\r\n<td width=\"500\"><img class=\"alignnone size-medium\" src=\"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/qv-43.jpg\" alt=\"\" width=\"100%\" \/><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>"},{"que_ver_contenido_acordeon_titulo":"Camposanto","que_ver_contenido_acordeon_descripcion":"<table cellpadding=\"20\">\r\n<tbody>\r\n<tr>\r\n<td>En el exterior, el jard\u00edn, antiguo camposanto, expone varias estelas funerarias de tipo discoideo, de los siglos XIII y XIV, que se rematan con cruces griegas en bajorrelieve y, probablemente, proceden de enterramientos de la primitiva iglesia que estaba junto al castillo, trasladadas para marcar los l\u00edmites del suelo sagrado de la nueva iglesia y su cementerio.\r\n\r\nHoy, bajo la advocaci\u00f3n de Nuestra Se\u00f1ora de las Nieves, la iglesia representa la grandeza como templo de la Villa que fue cabeza del Real de Manzanares.<\/td>\r\n<td width=\"500\"><img class=\"alignnone size-medium\" src=\"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/qv-44.jpg\" alt=\"\" width=\"100%\" \/><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>"}],"que_ver_contenido_extra_adicional":"","que_ver_galeria":[3195,3197,1038,1039,1040,1041,1042,1043,1044,1045,1052,1046,1047,1048,1049,1050,1051,3194,3196,3205,3198,3199,3200,3201,3202,3203,3204],"campos_plataforma":{"categoria_que_ver":["Cultural","Patrimonio","Religioso"],"subcategoria_que_ver":["Edificio religioso","Lugar hist\u00f3rico"],"duracion_que_ver":15,"tipo_de_viajero_que_ver":["Familiar","Mochilero","Senior"]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>que ver en manzanares el real - Patrimonio hist\u00f3rico y cultural<\/title>\n<meta name=\"description\" content=\"que ver en manzanares el real; desde su Patrimonio hist\u00f3rico a su Patrimonio natural o castillos medievales y mucho m\u00e1s \u00a1Vis\u00edtanos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"que ver en manzanares el real - Patrimonio hist\u00f3rico y cultural\" \/>\n<meta property=\"og:description\" content=\"que ver en manzanares el real; desde su Patrimonio hist\u00f3rico a su Patrimonio natural o castillos medievales y mucho m\u00e1s \u00a1Vis\u00edtanos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzanares el Real\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T10:35:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/\",\"name\":\"que ver en manzanares el real - Patrimonio hist\u00f3rico y cultural\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg\",\"datePublished\":\"2025-09-24T08:54:15+00:00\",\"dateModified\":\"2025-10-30T10:35:47+00:00\",\"description\":\"que ver en manzanares el real; desde su Patrimonio hist\u00f3rico a su Patrimonio natural o castillos medievales y mucho m\u00e1s \u00a1Vis\u00edtanos!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg\",\"contentUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/iglesia-de-nuestra-senora-de-las-nieves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 ver\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/que-ver\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Iglesia de Nuestra Se\u00f1ora de las Nieves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\",\"name\":\"Manzanares el Real\",\"description\":\"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"que ver en manzanares el real - Patrimonio hist\u00f3rico y cultural","description":"que ver en manzanares el real; desde su Patrimonio hist\u00f3rico a su Patrimonio natural o castillos medievales y mucho m\u00e1s \u00a1Vis\u00edtanos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/","og_locale":"es_ES","og_type":"article","og_title":"que ver en manzanares el real - Patrimonio hist\u00f3rico y cultural","og_description":"que ver en manzanares el real; desde su Patrimonio hist\u00f3rico a su Patrimonio natural o castillos medievales y mucho m\u00e1s \u00a1Vis\u00edtanos!","og_url":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/","og_site_name":"Manzanares el Real","article_modified_time":"2025-10-30T10:35:47+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/","url":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/","name":"que ver en manzanares el real - Patrimonio hist\u00f3rico y cultural","isPartOf":{"@id":"https:\/\/manzanareselreal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/#primaryimage"},"image":{"@id":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/#primaryimage"},"thumbnailUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg","datePublished":"2025-09-24T08:54:15+00:00","dateModified":"2025-10-30T10:35:47+00:00","description":"que ver en manzanares el real; desde su Patrimonio hist\u00f3rico a su Patrimonio natural o castillos medievales y mucho m\u00e1s \u00a1Vis\u00edtanos!","breadcrumb":{"@id":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/#primaryimage","url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg","contentUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/09\/06_IGLESIA-NUESTRA-SENORA-DE-LAS-NIEVES_DRON.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/manzanareselreal.org\/es\/que-ver\/iglesia-de-nuestra-senora-de-las-nieves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/manzanareselreal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 ver","item":"https:\/\/manzanareselreal.org\/es\/que-ver\/"},{"@type":"ListItem","position":3,"name":"Iglesia de Nuestra Se\u00f1ora de las Nieves"}]},{"@type":"WebSite","@id":"https:\/\/manzanareselreal.org\/es\/#website","url":"https:\/\/manzanareselreal.org\/es\/","name":"Manzanares el Real","description":"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manzanareselreal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/que-ver\/1032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/que-ver"}],"about":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/types\/que-ver"}],"version-history":[{"count":5,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/que-ver\/1032\/revisions"}],"predecessor-version":[{"id":3547,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/que-ver\/1032\/revisions\/3547"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3204"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3203"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3202"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3201"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3200"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3199"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3198"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3205"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3196"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3194"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1051"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1050"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1049"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1048"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1047"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1046"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1052"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1045"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1044"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1043"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1042"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1041"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1040"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1039"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/1038"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3197"},{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3194"}],"wp:attachment":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media?parent=1032"}],"wp:term":[{"taxonomy":"que-visitar","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/que-visitar?post=1032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}