{"id":3101,"date":"2025-10-21T18:45:16","date_gmt":"2025-10-21T16:45:16","guid":{"rendered":"https:\/\/openideas.site\/manzanareselreal\/es\/"},"modified":"2025-10-21T18:45:16","modified_gmt":"2025-10-21T16:45:16","slug":"la-pedriza-de-manzanares-club-deportivo-de-montana","status":"publish","type":"empresa","link":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/","title":{"rendered":"La Pedriza de Manzanares Club deportivo de monta\u00f1a"},"featured_media":3102,"parent":0,"template":"","format":"standard","meta":{"_acf_changed":false},"tipo-empresa":[43],"class_list":["post-3101","empresa","type-empresa","status-publish","format-standard","has-post-thumbnail","hentry","tipo-empresa-atencion-al-ciudadano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Pedriza de Manzanares Club deportivo de monta\u00f1a - Manzanares el Real<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Pedriza de Manzanares Club deportivo de monta\u00f1a - Manzanares el Real\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzanares el Real\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/10\/La-Pedriza-Club-Deportivo_Img1-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1952\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/\",\"name\":\"La Pedriza de Manzanares Club deportivo de monta\u00f1a - Manzanares el Real\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/La-Pedriza-Club-Deportivo_Img1-scaled.png\",\"datePublished\":\"2025-10-21T16:45:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/La-Pedriza-Club-Deportivo_Img1-scaled.png\",\"contentUrl\":\"https:\\\/\\\/manzanareselreal.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/La-Pedriza-Club-Deportivo_Img1-scaled.png\",\"width\":1952,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/empresa\\\/atencion-al-ciudadano\\\/la-pedriza-de-manzanares-club-deportivo-de-montana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atenci\u00f3n al ciudadano\",\"item\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/atencion-al-ciudadano\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Pedriza de Manzanares Club deportivo de monta\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/\",\"name\":\"Manzanares el Real\",\"description\":\"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manzanareselreal.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Pedriza de Manzanares Club deportivo de monta\u00f1a - Manzanares el Real","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/","og_locale":"es_ES","og_type":"article","og_title":"La Pedriza de Manzanares Club deportivo de monta\u00f1a - Manzanares el Real","og_url":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/","og_site_name":"Manzanares el Real","og_image":[{"width":1952,"height":2560,"url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/10\/La-Pedriza-Club-Deportivo_Img1-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/","url":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/","name":"La Pedriza de Manzanares Club deportivo de monta\u00f1a - Manzanares el Real","isPartOf":{"@id":"https:\/\/manzanareselreal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/#primaryimage"},"image":{"@id":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/#primaryimage"},"thumbnailUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/10\/La-Pedriza-Club-Deportivo_Img1-scaled.png","datePublished":"2025-10-21T16:45:16+00:00","breadcrumb":{"@id":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/#primaryimage","url":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/10\/La-Pedriza-Club-Deportivo_Img1-scaled.png","contentUrl":"https:\/\/manzanareselreal.org\/wp-content\/uploads\/2025\/10\/La-Pedriza-Club-Deportivo_Img1-scaled.png","width":1952,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/manzanareselreal.org\/es\/empresa\/atencion-al-ciudadano\/la-pedriza-de-manzanares-club-deportivo-de-montana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/manzanareselreal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Atenci\u00f3n al ciudadano","item":"https:\/\/manzanareselreal.org\/es\/atencion-al-ciudadano\/"},{"@type":"ListItem","position":3,"name":"La Pedriza de Manzanares Club deportivo de monta\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/manzanareselreal.org\/es\/#website","url":"https:\/\/manzanareselreal.org\/es\/","name":"Manzanares el Real","description":"En el Parque Nacional de la Sierra de Guadarrama, al pie de La Pedriza, llegar a este municipio de la Sierra Norte es sumergirse en la historia y la naturaleza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manzanareselreal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/empresa\/3101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/empresa"}],"about":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/types\/empresa"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media\/3102"}],"wp:attachment":[{"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/media?parent=3101"}],"wp:term":[{"taxonomy":"tipo-empresa","embeddable":true,"href":"https:\/\/manzanareselreal.org\/es\/wp-json\/wp\/v2\/tipo-empresa?post=3101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}